{"id":1451,"date":"2018-12-02T07:58:58","date_gmt":"2018-12-02T07:58:58","guid":{"rendered":"http:\/\/template-new.template.cmsmasters.net\/?p=24"},"modified":"2022-04-29T14:19:19","modified_gmt":"2022-04-29T14:19:19","slug":"exzellentes-essen","status":"publish","type":"post","link":"https:\/\/oparquedosleitoes.pt\/de\/2018\/12\/02\/exzellentes-essen\/","title":{"rendered":"Exzellentes Essen"},"content":{"rendered":"<div id=\"cmsmasters_row_\" class=\"cmsmasters_row cmsmasters_color_scheme_default cmsmasters_row_top_default cmsmasters_row_bot_default cmsmasters_row_boxed\">\n<div class=\"cmsmasters_row_outer_parent\">\n<div class=\"cmsmasters_row_outer\">\n<div class=\"cmsmasters_row_inner\">\n<div class=\"cmsmasters_row_margin\">\n<div id=\"cmsmasters_column_\" class=\"cmsmasters_column one_first\">\n<div class=\"cmsmasters_column_inner\"><div class=\"cmsmasters_text\">\n<p style=\"text-align: left;\">Exzellentes Essen. Extrem aufmerksames Personal und au\u00dfergew\u00f6hnliche Atmosph\u00e4re. Sowohl das Zimmer als auch die Terrasse sind \u00e4u\u00dferst angenehm. Sicher zu wiederholen.<\/p>\n<\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>Excelente comida. Staff extremamente atencioso e ambiente extraordin\u00e1rio.. Tanto a sala como a esplanada s\u00e3o extremamente agrad\u00e1veis. A repetir com toda a certeza.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[23],"tags":[],"class_list":["post-1451","post","type-post","status-publish","format-standard","hentry","category-testemunhos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Exzellentes Essen - O Parque dos Leit\u00f5es<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Exzellentes Essen - O Parque dos Leit\u00f5es\" \/>\n<meta property=\"og:description\" content=\"Excelente comida. Staff extremamente atencioso e ambiente extraordin\u00e1rio.. Tanto a sala como a esplanada s\u00e3o extremamente agrad\u00e1veis. A repetir com toda a certeza.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/oparquedosleitoes.pt\/de\/2018\/12\/02\/exzellentes-essen\/\" \/>\n<meta property=\"og:site_name\" content=\"O Parque dos Leit\u00f5es\" \/>\n<meta property=\"article:published_time\" content=\"2018-12-02T07:58:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-04-29T14:19:19+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"oparquedosleitoes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/oparquedosleitoes.pt\/de\/#website\",\"url\":\"https:\/\/oparquedosleitoes.pt\/de\/\",\"name\":\"O Parque dos Leit\u00f5es\",\"description\":\"Restaurante Arraiolos e \u00c9vora\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/oparquedosleitoes.pt\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/oparquedosleitoes.pt\/de\/2018\/12\/02\/exzellentes-essen\/#webpage\",\"url\":\"https:\/\/oparquedosleitoes.pt\/de\/2018\/12\/02\/exzellentes-essen\/\",\"name\":\"Exzellentes Essen - O Parque dos Leit\u00f5es\",\"isPartOf\":{\"@id\":\"https:\/\/oparquedosleitoes.pt\/de\/#website\"},\"datePublished\":\"2018-12-02T07:58:58+00:00\",\"dateModified\":\"2022-04-29T14:19:19+00:00\",\"author\":{\"@id\":\"https:\/\/oparquedosleitoes.pt\/de\/#\/schema\/person\/0b4518645165a9924eebb4c2fa947c45\"},\"breadcrumb\":{\"@id\":\"https:\/\/oparquedosleitoes.pt\/de\/2018\/12\/02\/exzellentes-essen\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/oparquedosleitoes.pt\/de\/2018\/12\/02\/exzellentes-essen\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/oparquedosleitoes.pt\/de\/2018\/12\/02\/exzellentes-essen\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/oparquedosleitoes.pt\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Exzellentes Essen\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/oparquedosleitoes.pt\/de\/#\/schema\/person\/0b4518645165a9924eebb4c2fa947c45\",\"name\":\"oparquedosleitoes\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/oparquedosleitoes.pt\/de\/#personlogo\",\"inLanguage\":\"pt-PT\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1e26d47a7475da597a41e814a6f6ca755292a3ea92eaddb5d516cf1dd098de1a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1e26d47a7475da597a41e814a6f6ca755292a3ea92eaddb5d516cf1dd098de1a?s=96&d=mm&r=g\",\"caption\":\"oparquedosleitoes\"},\"sameAs\":[\"https:\/\/oparquedosleitoes.pt\/de\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Exzellentes Essen - O Parque dos Leit\u00f5es","robots":{"index":"noindex","follow":"follow"},"og_locale":"pt_PT","og_type":"article","og_title":"Exzellentes Essen - O Parque dos Leit\u00f5es","og_description":"Excelente comida. Staff extremamente atencioso e ambiente extraordin\u00e1rio.. Tanto a sala como a esplanada s\u00e3o extremamente agrad\u00e1veis. A repetir com toda a certeza.","og_url":"https:\/\/oparquedosleitoes.pt\/de\/2018\/12\/02\/exzellentes-essen\/","og_site_name":"O Parque dos Leit\u00f5es","article_published_time":"2018-12-02T07:58:58+00:00","article_modified_time":"2022-04-29T14:19:19+00:00","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"oparquedosleitoes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/oparquedosleitoes.pt\/de\/#website","url":"https:\/\/oparquedosleitoes.pt\/de\/","name":"O Parque dos Leit\u00f5es","description":"Restaurante Arraiolos e \u00c9vora","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/oparquedosleitoes.pt\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/oparquedosleitoes.pt\/de\/2018\/12\/02\/exzellentes-essen\/#webpage","url":"https:\/\/oparquedosleitoes.pt\/de\/2018\/12\/02\/exzellentes-essen\/","name":"Exzellentes Essen - O Parque dos Leit\u00f5es","isPartOf":{"@id":"https:\/\/oparquedosleitoes.pt\/de\/#website"},"datePublished":"2018-12-02T07:58:58+00:00","dateModified":"2022-04-29T14:19:19+00:00","author":{"@id":"https:\/\/oparquedosleitoes.pt\/de\/#\/schema\/person\/0b4518645165a9924eebb4c2fa947c45"},"breadcrumb":{"@id":"https:\/\/oparquedosleitoes.pt\/de\/2018\/12\/02\/exzellentes-essen\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/oparquedosleitoes.pt\/de\/2018\/12\/02\/exzellentes-essen\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/oparquedosleitoes.pt\/de\/2018\/12\/02\/exzellentes-essen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/oparquedosleitoes.pt\/de\/"},{"@type":"ListItem","position":2,"name":"Exzellentes Essen"}]},{"@type":"Person","@id":"https:\/\/oparquedosleitoes.pt\/de\/#\/schema\/person\/0b4518645165a9924eebb4c2fa947c45","name":"oparquedosleitoes","image":{"@type":"ImageObject","@id":"https:\/\/oparquedosleitoes.pt\/de\/#personlogo","inLanguage":"pt-PT","url":"https:\/\/secure.gravatar.com\/avatar\/1e26d47a7475da597a41e814a6f6ca755292a3ea92eaddb5d516cf1dd098de1a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1e26d47a7475da597a41e814a6f6ca755292a3ea92eaddb5d516cf1dd098de1a?s=96&d=mm&r=g","caption":"oparquedosleitoes"},"sameAs":["https:\/\/oparquedosleitoes.pt\/de"]}]}},"_links":{"self":[{"href":"https:\/\/oparquedosleitoes.pt\/de\/wp-json\/wp\/v2\/posts\/1451","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/oparquedosleitoes.pt\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/oparquedosleitoes.pt\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/oparquedosleitoes.pt\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/oparquedosleitoes.pt\/de\/wp-json\/wp\/v2\/comments?post=1451"}],"version-history":[{"count":4,"href":"https:\/\/oparquedosleitoes.pt\/de\/wp-json\/wp\/v2\/posts\/1451\/revisions"}],"predecessor-version":[{"id":1779,"href":"https:\/\/oparquedosleitoes.pt\/de\/wp-json\/wp\/v2\/posts\/1451\/revisions\/1779"}],"wp:attachment":[{"href":"https:\/\/oparquedosleitoes.pt\/de\/wp-json\/wp\/v2\/media?parent=1451"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/oparquedosleitoes.pt\/de\/wp-json\/wp\/v2\/categories?post=1451"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/oparquedosleitoes.pt\/de\/wp-json\/wp\/v2\/tags?post=1451"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}